{"id":5475,"date":"2019-01-16T02:27:17","date_gmt":"2019-01-16T10:27:17","guid":{"rendered":"http:\/\/aaugh.com\/wordpress\/?post_type=podcast&#038;p=5475"},"modified":"2019-01-15T21:41:46","modified_gmt":"2019-01-16T05:41:46","slug":"aaugh-collectors-guides","status":"publish","type":"podcast","link":"https:\/\/aaugh.com\/wordpress\/podcast\/aaugh-collectors-guides\/","title":{"rendered":"AAUGH: Collectors&#8217; Guides"},"content":{"rendered":"<p>Collecting Peanuts stuff is a hobby, and as with any good hobby, there are books about it. In this episode, Peanuts book collector Nat Gertler, the AAUGH Blogger, looks at some Peanuts collectors guides.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Collecting Peanuts stuff is a hobby, and as with any good hobby, there are books about it. In this episode, Peanuts book collector Nat Gertler, the AAUGH Blogger, looks at some Peanuts collectors guides.<\/p>\n","protected":false},"author":1,"featured_media":5476,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","episode_type":"audio","audio_file":"http:\/\/aaugh.com\/wordpress\/wp-content\/uploads\/2019\/01\/AAUGH65CollectorsGuides.mp3","cover_image":"","cover_image_id":"","duration":"13:00","filesize":"6.3 MB","date_recorded":"15-01-2019","explicit":"","block":"","itunes_episode_number":"65","itunes_title":"Collectors' Guide","itunes_season_number":"","itunes_episode_type":"full","filesize_raw":"6306524"},"tags":[],"series":[36],"class_list":["post-5475","podcast","type-podcast","status-publish","has-post-thumbnail","hentry","series-the-aaugh-blog-podcast"],"episode_featured_image":"https:\/\/aaugh.com\/wordpress\/wp-content\/uploads\/2019\/01\/with-values.jpeg","episode_player_image":"https:\/\/aaugh.com\/wordpress\/wp-content\/uploads\/2017\/10\/AAUGHBlogPodcastlogo.jpg","download_link":"https:\/\/aaugh.com\/wordpress\/podcast-download\/5475\/aaugh-collectors-guides.mp3","player_link":"https:\/\/aaugh.com\/wordpress\/podcast-player\/5475\/aaugh-collectors-guides.mp3","audio_player":"<audio class=\"wp-audio-shortcode\" id=\"audio-5475-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/aaugh.com\/wordpress\/podcast-player\/5475\/aaugh-collectors-guides.mp3?_=1\" \/><a href=\"https:\/\/aaugh.com\/wordpress\/podcast-player\/5475\/aaugh-collectors-guides.mp3\">https:\/\/aaugh.com\/wordpress\/podcast-player\/5475\/aaugh-collectors-guides.mp3<\/a><\/audio>","episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/aaugh.com\/wordpress\/feed\/podcast\/the-aaugh-blog-podcast","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"goWu1hY4bF\"><a href=\"https:\/\/aaugh.com\/wordpress\/podcast\/aaugh-collectors-guides\/\">AAUGH: Collectors&#8217; Guides<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/aaugh.com\/wordpress\/podcast\/aaugh-collectors-guides\/embed\/#?secret=goWu1hY4bF\" width=\"500\" height=\"350\" title=\"&#8220;AAUGH: Collectors&#8217; Guides&#8221; &#8212; The AAUGH Blog\" data-secret=\"goWu1hY4bF\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/aaugh.com\/wordpress\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/podcast\/5475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/comments?post=5475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/media\/5476"}],"wp:attachment":[{"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/media?parent=5475"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/tags?post=5475"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/aaugh.com\/wordpress\/wp-json\/wp\/v2\/series?post=5475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}